{"id":862,"date":"2017-01-11T16:09:11","date_gmt":"2017-01-11T15:09:11","guid":{"rendered":"http:\/\/nf.dpin.de\/?p=862"},"modified":"2017-01-11T16:09:11","modified_gmt":"2017-01-11T15:09:11","slug":"maassen-digitale-gegenangriffe-verfassung-nicht-verstanden","status":"publish","type":"post","link":"https:\/\/www.dpin.de\/nf\/maassen-digitale-gegenangriffe-verfassung-nicht-verstanden\/","title":{"rendered":"Maa\u00dfen: Digitale Gegenangriffe &#8211; Verfassung nicht verstanden!"},"content":{"rendered":"<p>Unser Minister f\u00fcr Verfassungsschutz, Hans-Georg Ma\u00dfen, forderte gerade <em>&#8222;Wir m\u00fcssen auch in der Lage sein, den Gegner anzugreifen, damit er aufh\u00f6rt, uns weiter zu attackieren&#8220;<\/em> (Quelle: dpa). In ein \u00e4hnliches Horn stie\u00df k\u00fcrzlich auch Innenminister De Maizi\u00e8re. Neben eine Zentralisierung des Verfassungsschutzes in einer Bundesbeh\u00f6rde sprach er auch von <em>&#8222;aktiven Gegenma\u00dfnahmen und Gegenangriffen&#8220;<\/em> im Fall von digitalen Angriffen von au\u00dfen. Beide haben die Lage und technischen Grundlagen offenbar \u00fcberhaupt nicht verstanden. Constanze Kurz, Sprecherin des Chaos Computer Club, nannte diese Forderungen <em>&#8222;technisch bemerkenswert ahnungslos und zudem gef\u00e4hrlich&#8220;<\/em>.<\/p>\n<p>Beide haben offenbar unsere Verfassung, das Grundgesetz, entweder nicht gelesen oder nicht verstanden. In Artikel 26 Absatz 1 hei\u00dft es ausdr\u00fccklich:<\/p>\n<blockquote><p>Handlungen, die geeignet sind und in der Absicht vorgenommen werden, das friedliche Zusammenleben der V\u00f6lker zu st\u00f6ren, insbesondere die F\u00fchrung eines Angriffskrieges vorzubereiten, sind verfassungswidrig. Sie sind unter Strafe zu stellen.<\/p><\/blockquote>\n<p>Jetzt kann man sich nat\u00fcrlich dar\u00fcber streiten, ob ein Angriff in der digitalen Welt eine kriegerische Handlung darstellt, doch hier wird zur Zeit offenbar auch mit zweierlei Ma\u00df gemessen. Auf der einen Seite werden Angriffe auf die digitale Infrastruktur mit Kriegsrethorik beschrieben und nun auch gleicherma\u00dfen m\u00f6gliche Gegenma\u00dfnahmen, auf der anderen Seite solle dies aber keine kriegerische Handlung sein, um GG \u00a726(1) zu entkommen?<\/p>\n<p>Das kann nicht sein. Wir sehen die m\u00f6glichen Auswirkungen dieser Art von digitaler Kriegsf\u00fchrung bereits mehr als deutlich und sie f\u00fchren im virtuellen Raum zu den gleichen Eskalationen, wie in der realen Welt. Nur gibt es im digitalen Raum einen gro\u00dfen Unterschied zum realen Raum, sowohl Angreifer als auch die Auswirkungen einer Vergeltung k\u00f6nnen nicht kontrolliert werden. Wie Constanze Kurz andeutete, es ist extrem komplex und problematisch, die wahren Verursacher m\u00f6glicher Attacken tats\u00e4chlich ausfindig zu machen. Nur weil in Logs eine IP Adresse aus einem Land auftaucht, bedeutet das noch lange nicht, dass der Geheimdienst dieses Landes diesen Angriff beauftragt habe. Es ist sogar nicht einmal eindeutig feststellbar, ob diese Quelladresse tats\u00e4chlich die Quelladresse des Verursachers \/ Angreifers ist! Dieser k\u00f6nnte auch tausende Kilometer weit entfernt in einem ganz anderen Land sitzen und diesen Rechner schlicht fernsteuern. Gleicherma\u00dfen sind die Auswirkungen eines &#8222;Vergeltungsschlages&#8220; auf weitgehend unbekannte IT Infrastruktur v\u00f6llig unvorhersehbar &#8211; und man wei\u00df \u00fcberhaupt nicht, ob man damit \u00fcberhaupt diejenigen trifft, die man treffen m\u00f6chte. Es k\u00f6nnten genauso gut auch v\u00f6llig unbeteiligte Zivilist_innen sein oder, schlimmer noch, kritische Infrastruktur, die dann Zivilist_innen in konkrete Gefahr bringt.<\/p>\n<p>Und bitte komme mir jetzt keiner mit &#8222;Aber das sind doch Beh\u00f6rden, die wissen was sie tun und besch\u00e4ftigen die Besten der Besten!&#8220; &#8211; nein, sie wissen es nicht und sie besch\u00e4ftigen einen IT Bodensatz, der sich nicht zu schade ist, f\u00fcr solche Beh\u00f6rden, wie den Verfassungsschutz, BND oder das BKA, zu arbeiten. Wie toll die das machen haben wir bereits gesehen, am Bundes-Trojaner, dem Totalversagen im Bundestag und der gro\u00dfartigen Arbeit bei der Bespitzelung der eigenen B\u00fcrger (vgl. Snowden Affaire). Und *die* sollen pr\u00e4zise Informationen \u00fcber die Angreifer produzieren? Pr\u00e4zise Ziele und Methode definieren k\u00f6nnen? Dies auch durchf\u00fchren k\u00f6nnen? Nie im Leben! Was dann passiert ist, dass so tolle Firmen wie <a href=\"https:\/\/www.heise.de\/thema\/Hacking-Team\" target=\"_blank\">Hacking Team<\/a> oder <a href=\"https:\/\/de.wikipedia.org\/wiki\/FinFisher\" target=\"_blank\">FinFisher<\/a> engagiert werden, privatwirtschaftliche Unternehmen, mit noch ganz anderen Interessen.<\/p>\n<p>Nein, Finger weg, das ist ein \u00e4u\u00dferst gewagtes Spiel mit dem Feuer und unabsehbaren Folgen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unser Minister f\u00fcr Verfassungsschutz, Hans-Georg Ma\u00dfen, forderte gerade &#8222;Wir m\u00fcssen auch in der Lage sein, den Gegner anzugreifen, damit er aufh\u00f6rt, uns weiter zu attackieren&#8220; (Quelle: dpa). In ein \u00e4hnliches Horn stie\u00df k\u00fcrzlich auch Innenminister De Maizi\u00e8re. Neben eine Zentralisierung des Verfassungsschutzes in einer Bundesbeh\u00f6rde sprach er auch von &#8222;aktiven Gegenma\u00dfnahmen und Gegenangriffen&#8220; im Fall von digitalen Angriffen von au\u00dfen&#8230;. <a href=\"https:\/\/www.dpin.de\/nf\/maassen-digitale-gegenangriffe-verfassung-nicht-verstanden\/\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,4],"tags":[],"class_list":["post-862","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-politik-gesellschaft"],"_links":{"self":[{"href":"https:\/\/www.dpin.de\/nf\/wp-json\/wp\/v2\/posts\/862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dpin.de\/nf\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dpin.de\/nf\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dpin.de\/nf\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dpin.de\/nf\/wp-json\/wp\/v2\/comments?post=862"}],"version-history":[{"count":0,"href":"https:\/\/www.dpin.de\/nf\/wp-json\/wp\/v2\/posts\/862\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dpin.de\/nf\/wp-json\/wp\/v2\/media?parent=862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dpin.de\/nf\/wp-json\/wp\/v2\/categories?post=862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dpin.de\/nf\/wp-json\/wp\/v2\/tags?post=862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}